{"id":61579,"date":"2023-09-19T13:17:42","date_gmt":"2023-09-19T12:17:42","guid":{"rendered":"https:\/\/www.aube-champagne.com\/?page_id=61579"},"modified":"2026-02-16T16:43:01","modified_gmt":"2026-02-16T15:43:01","slug":"la-fresque-de-lhuitre","status":"publish","type":"page","link":"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/","title":{"rendered":"Parcours Rachi : La fresque de Lhu\u00eetre"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_single_image image=\u00a0\u00bb69125&Prime; img_size=\u00a0\u00bb2048&#215;1200&Prime;][vc_row_inner][vc_column_inner][vc_column_text]\n<p style=\"text-align: center;\">La fresque \u00ab\u00a0Rachi, ses disciples et ses filles \u00bb, cr\u00e9\u00e9e en septembre 2023, raconte et met en valeur le patrimoine juif m\u00e9di\u00e9val de Lhu\u00eetre o\u00f9 une communaut\u00e9 juive est install\u00e9e au Moyen-\u00c2ge du temps des comtes de Champagne.<\/p>\n<p style=\"text-align: center;\"><strong>\u00a0<\/strong>Cette fresque est la troisi\u00e8me d\u2019un circuit de slowtourisme, qui sera enrichi dans les prochaines ann\u00e9es avec la cr\u00e9ation de plusieurs fresques dans une vingtaine d\u2019autres villes et villages de l\u2019Aube. L\u2019\u00e9crit, fruit du travail intellectuel que nous ont l\u00e9gu\u00e9 les Sages de Champagne, constitue le fil conducteur de ce \u00ab\u00a0Parcours Rachi\u00a0\u00bb.<\/p>\n<p style=\"text-align: center;\">Originale dans sa conception, cette initiative engag\u00e9e donne un coup de projecteur \u00e0 des communes rurales autour d\u2019un projet collaboratif historique, artistique, culturel, touristique et citoyen inattendu, rassembleur autour de valeurs fortes\u00a0: partage, ouverture intellectuelle, curiosit\u00e9 artistique, lutte contre les st\u00e9r\u00e9otypes, le racisme et l\u2019antis\u00e9mitisme.<\/p>\n<p style=\"text-align: center;\">La fresque de Lhu\u00eetre mesure 3.80m sur 2.75m et se situe sur le mur de la Mairie.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00a0\u00bb16px\u00a0\u00bb][vc_separator color=\u00a0\u00bborange\u00a0\u00bb el_width=\u00a0\u00bb30&Prime;][vc_empty_space height=\u00a0\u00bb16px\u00a0\u00bb][vc_row_inner][vc_column_inner][vc_column_text]\n<h2 style=\"text-align: left;\"><strong>Quels sont les \u00e9l\u00e9ments constitutifs de cette fresque?<\/strong><\/h2>\n[\/vc_column_text][vc_column_text]Le patrimoine juif m\u00e9di\u00e9val de Champagne est largement immat\u00e9riel. Pourtant les commentaires de Rachi &#8211; personnage phare de la pens\u00e9e juive m\u00e9di\u00e9vale &#8211; et de ses disciples, les Tossafistes (commentateurs de l\u2019Ecole de Rachi), sur la Bible et le Talmud sont encore \u00e9tudi\u00e9s dans le monde entier.<\/p>\n<p>Aussi, le \u00ab\u00a0Parcours Rachi\u00a0\u00bb port\u00e9 par la Route M\u00e9di\u00e9vale de Rachi en Champagne s\u2019appuie sur ces personnages historiques install\u00e9s dans des communaut\u00e9s locales qui constitu\u00e8rent un terrain propice \u00e0 la rencontre entre communaut\u00e9s juives et chr\u00e9tiennes partageant un quotidien commun. Leur cr\u00e9ativit\u00e9 put s\u2019y \u00e9panouir pour donner naissance \u00e0 des \u00e9crits qui restent des r\u00e9f\u00e9rences aujourd\u2019hui.[\/vc_column_text][vc_column_text]\n<h3><strong>Rencontre entre h\u00e9breu et champenois, entre juda\u00efsme et Champagne<\/strong><\/h3>\n[\/vc_column_text][vc_column_text]Pour exprimer ces \u00e9changes quotidiens et familiers, chaque fresque du \u00ab\u00a0Parcours Rachi\u00a0\u00bb contient un commentaire de Rachi en h\u00e9breu, traduit en fran\u00e7ais. Ces commentaires comportent de tr\u00e8s nombreux t\u00e9moignages de la vie locale de l\u2019\u00e9poque.<\/p>\n<p>Le fran\u00e7ais m\u00e9di\u00e9val \u00e9tait la langue maternelle des juifs champenois. Ils utilisaient l\u2019h\u00e9breu pour le culte et l\u2019\u00e9tude des textes sacr\u00e9s et ins\u00e9raient des mots en fran\u00e7ais dans leurs commentaires pour en faciliter la compr\u00e9hension par leurs lecteurs et disciples.<\/p>\n<p>Ainsi, au travers de leurs commentaires, le fran\u00e7ais m\u00e9di\u00e9val a travers\u00e9 les fronti\u00e8res et les si\u00e8cles pour devenir un t\u00e9moignage majeur des pr\u00e9mices de notre langue. Ces mots constituent parfois les plus anciens exemples de termes transcrits en ancien fran\u00e7ais et figurent dans de nombreux dictionnaires.<\/p>\n<p>Pour illustrer \u00e0 la fois cette transmission de l\u2019histoire et de la langue, le commentaire choisi pour la fresque de Lhu\u00eetre porte sur le verset Deut\u00e9ronome 14, 12-18 de la Bible h\u00e9bra\u00efque\u00a0:<\/p>\n<p><em>\u00ab\u00a0Voici [les animaux] que vous ne mangerez point: l&rsquo;aigle, l&rsquo;orfraie, la val\u00e9rie,\u00a0le faucon, les vari\u00e9t\u00e9s de vautours,\u00a0tous les corbeaux,\u00a0l&rsquo;autruche, l&rsquo;hirondelle, la mouette, les vari\u00e9t\u00e9s d\u2019\u00e9perviers, le hibou, la hulotte, le porphyrion, le p\u00e9lican, le percnopt\u00e8re, le cormoran,\u00a0<\/em><em>la cigogne, les vari\u00e9t\u00e9s de h\u00e9rons, la huppe et la chauve-souris<\/em><em>.<\/em><em>\u00a0\u00bb.<\/em><\/p>\n<p>Rachi commente ce passage comme suit\u00a0:<\/p>\n<p><em>\u00ab<\/em><em> La huppe est le coq sauvage, qui est appel\u00e9 <strong>harupe <\/strong>dans notre langue et qui a une cr\u00eate double\u00a0<\/em><em>\u00bb.<\/em><\/p>\n<p>Ce commentaire de Rachi utilise le mot harupe en ancien fran\u00e7ais, transcrit en caract\u00e8res h\u00e9bra\u00efques pour traduire le mot huppe.<\/p>\n<p>La traduction du commentaire est une adaptation de plusieurs sources qui a permis de rendre sa lecture et la compr\u00e9hension plus fluide.<\/p>\n<p>Ce commentaire confirme le lien entre le quotidien m\u00e9di\u00e9val en Champagne et l\u2019\u00e9tude du texte biblique par les communaut\u00e9s juives pr\u00e9sentes sur le territoire.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb61593&Prime; img_size=\u00a0\u00bb568&#215;426&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb61590&Prime; img_size=\u00a0\u00bb568&#215;426&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<h3 style=\"text-align: left;\"><strong>La narration de la fresque de Lhu\u00eetre<\/strong><\/h3>\n[\/vc_column_text][vc_column_text]A ce jour, Lhu\u00eetre est r\u00e9f\u00e9renc\u00e9e comme l\u2019une des communes ayant abrit\u00e9 une communaut\u00e9 juive m\u00e9di\u00e9vale. Apr\u00e8s Rachi, c\u00e9l\u00e8bre commentateur des textes sacr\u00e9s du juda\u00efsme, son Ecole rayonne depuis le comt\u00e9 de Champagne \u00e0 partir du XIIe si\u00e8cle. Au XIIIe si\u00e8cle, le territoire a compt\u00e9 jusqu\u2019\u00e0 70 \u00e9rudits qui ont donn\u00e9 leurs lettres de noblesse au Talmud en s\u2019inspirant de la m\u00e9thode de Rachi.<\/p>\n<p>Aucun nom de Tossafistes ou de membres de la communaut\u00e9 juive de Lhu\u00eetre ne nous est parvenu \u00e0 ce jour. A d\u00e9faut, la fresque repr\u00e9sente Rachi, sa femme et ses filles ainsi que ses disciples.[\/vc_column_text][vc_column_text]\n<h3 style=\"text-align: left;\"><strong>Les personnages<\/strong><\/h3>\n[\/vc_column_text][vc_column_text]Rachi, n\u00e9 en 1040 et mort en 1105, est repr\u00e9sent\u00e9 ici \u00e2g\u00e9 et serein, concentr\u00e9 sur un passage biblique qu\u2019il d\u00e9chiffre. L\u2019artiste a imagin\u00e9 une huppe lui soufflant des mots sacr\u00e9s \u00e0 l\u2019oreille. La huppe fasci\u00e9e a \u00e9t\u00e9 le symbole de l\u2019\u00c9tat d\u2019Isra\u00ebl en 2008. Cet oiseau end\u00e9mique du territoire de Champagne a \u00e9t\u00e9 d\u00e9crit par Rachi dans le verset biblique du Deut\u00e9ronome 14, 18 et du L\u00e9vitique 11, 19 tel qu\u2019\u00e9nonc\u00e9 plus haut.<\/p>\n<p>Au cours de sa vie Rachi a enseign\u00e9 \u00e0 une vingtaine d\u2019\u00e9l\u00e8ves venus de France du Nord et au-del\u00e0. Ils \u00e9tudiaient chez le Ma\u00eetre et s\u2019inspiraient de sa nouvelle m\u00e9thode de commentaires avant de s\u2019installer \u00e0 leur tour dans d\u2019autres territoires, pour ouvrir une maison d\u2019\u00e9tudes o\u00f9 ils transmettaient l\u2019enseignement de Rachi et les paroles de Torah. Ils sont ici repr\u00e9sent\u00e9s tous ensemble autour d\u2019une table anim\u00e9e de discussions.<\/p>\n<p>Son \u00e9pouse, dont on ignore le pr\u00e9nom, et ses trois filles, Myriam, Yochebed et Rachel apparaissent au premier plan, un manuscrit et des instruments de musique \u00e0 la main, afin de montrer, comme l\u2019a sugg\u00e9r\u00e9 le Professeur et rabbin Marc-Alain Ouaknin, l\u2019importance qu\u2019a donn\u00e9 Rachi \u00e0 l\u2019\u00e9tude des femmes en son temps. Ses filles \u00e9taient instruites et savantes. Elles \u00e9taient consult\u00e9es sur des questions d\u2019ex\u00e9g\u00e8se biblique. L\u2019existence de sa troisi\u00e8me fille, Rachel, reste controvers\u00e9e selon certaines sources.<\/p>\n<p>Sur le m\u00eame plan, la patronne de Lhu\u00eetre, sainte Tanche, repr\u00e9sente une autre figure f\u00e9minine forte du territoire. Martyre d\u00e9capit\u00e9e en 637, elle appara\u00eet devant la chapelle qui porte son nom et qui se visite aujourd\u2019hui.<\/p>\n<p>Cette repr\u00e9sentation de femmes juives et chr\u00e9tienne sur le m\u00eame plan, symbolise la rencontre entre Juda\u00efsme et Christianisme en terre de Champagne. Les Juifs et Chr\u00e9tiens ont partag\u00e9 la m\u00eame langue, les m\u00eames m\u00e9tiers et les m\u00eames quartiers jusqu\u2019au XIII<sup>e<\/sup> si\u00e8cle et leurs relations dans le comt\u00e9 de Champagne \u00e9taient plut\u00f4t favorables.<\/p>\n<p>Tous les personnages symbolisent \u00e9galement l\u2019importance de l\u2019\u00e9tude, de la foi et de la transmission.<\/p>\n<p>Ils apparaissent autour de travaux des champs, leur moyen de subsistance principal. La r\u00e9gion de Lhu\u00eetre est historiquement une r\u00e9gion agricole, terre de bl\u00e9s, de vigne et d\u2019\u00e9levage. C\u2019est la raison pour laquelle il a \u00e9t\u00e9 choisi de repr\u00e9senter ces symboles forts de l\u2019identit\u00e9 locale \u00e0 diff\u00e9rents endroits de la fresque.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_empty_space height=\u00a0\u00bb16px\u00a0\u00bb][vc_single_image image=\u00a0\u00bb61596&Prime; img_size=\u00a0\u00bb568&#215;568&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]\n<h3 style=\"text-align: left;\"><strong>Le contenu des frises<\/strong><\/h3>\n[\/vc_column_text][vc_column_text]Sur le bandeau sup\u00e9rieur, le symbole d\u2019une m\u00e9nora est r\u00e9p\u00e9t\u00e9 8 fois. La m\u00e9nora est un objet liturgique juif tr\u00e8s ancien qui signifie \u00ab\u00a0cand\u00e9labre\u00a0\u00bb dont la description appara\u00eet dans la Bible au chapitre de l\u2019Exode 25, 21-37, dont la cr\u00e9ation a \u00e9t\u00e9 demand\u00e9e par Dieu. Elle repr\u00e9sente un objet biblique \u00e9galement devenu symbole de l\u2019Etat d\u2019Isra\u00ebl. Elle porte 7 branches comme un arbre qui s\u2019\u00e9l\u00e8ve vers le ciel avec des fruits de lumi\u00e8re qui rayonnent vers l\u2019ext\u00e9rieur, \u00ab\u00a0un arbre de vie qui \u00e9claire celui qui \u00e9tudie\u00a0\u00bb selon Rachi. Les 7 branches sont comme les sept jours de la semaine dont le Chabbat, le jour sacr\u00e9 pour les Juifs, au centre, \u00e9claire tous les autres. Sur la fresque, la m\u00e9nora est sugg\u00e9r\u00e9e po\u00e9tiquement avec seulement 3 branches.<\/p>\n<p>&nbsp;<\/p>\n<p>Sur les bandeaux des deux c\u00f4t\u00e9s, apparait l\u2019alphabet h\u00e9breu dans une police particuli\u00e8re appel\u00e9e \u00ab\u00a0Ecriture Rachi\u00a0\u00bb. L\u2019alphabet h\u00e9breu compte 22 lettres. Les caract\u00e8res Rachi sont des caract\u00e8res utilis\u00e9s \u00e0 partir du XVI<sup>e<\/sup> si\u00e8cle pour l\u2019impression des commentaires de Rachi et des Tossafistes, afin de les distinguer des caract\u00e8res dits \u00ab\u00a0carr\u00e9s\u00a0\u00bb dans lesquels \u00e9taient imprim\u00e9s les paroles sacr\u00e9es de la Bible et du Talmud afin de les diff\u00e9rencier des commentaires. Seuls Rachi et les Tossafistes sont depuis, imprim\u00e9s dans ce caract\u00e8re sp\u00e9cifique d\u2019imprimerie, qui s\u2019est inspir\u00e9 d\u2019une ancienne cursive h\u00e9bra\u00efque s\u00e9farade ant\u00e9rieure \u00e0 Rachi. Autour de l\u2019alphabet, les \u00e9pis de bl\u00e9 rappellent qu\u2019ils sont \u00e0 la fois l\u2019un des 7 fruits d\u2019Isra\u00ebl mentionn\u00e9s dans la Bible et \u00e9galement le symbole de l\u2019agriculture locale.<\/p>\n<p>Sur le ruban du bas d\u00e9file la Lhuitrelle, la rivi\u00e8re qui traverse le village. Elle est surplomb\u00e9e de grappes de raisin, qui poussaient jadis dans la r\u00e9gion. Un petit pont de pierre symbolise au centre, \u00e0 la fois le lien entre pass\u00e9 et pr\u00e9sent, la transmission, et les \u00e9changes entre Juifs et Chr\u00e9tiens au Moyen-\u00c2ge.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u00a0\u00bb16px\u00a0\u00bb][vc_separator color=\u00a0\u00bborange\u00a0\u00bb el_width=\u00a0\u00bb30&Prime;][vc_empty_space height=\u00a0\u00bb16px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner][vc_column_text]\n<h2 style=\"text-align: left;\"><strong>Les origines du Parcours Rachi\u00a0<\/strong><\/h2>\n[\/vc_column_text][vc_column_text]Depuis 2019, la Champagne fait partie de la Route du patrimoine juif, Itin\u00e9raire Culturel du\u00a0Conseil de l\u2019Europe, en tant que berceau d\u2019un patrimoine immat\u00e9riel universellement connu et reconnu. La Route M\u00e9di\u00e9vale de Rachi en Champagne a pour mission de faire rayonner la m\u00e9moire juive du d\u00e9partement de l\u2019Aube,\u00a0patrimoine culturel d\u2019une valeur inestimable partag\u00e9 par les Juifs du monde entier et patrimoine historique d\u2019un territoire de tout premier plan \u2013 l\u2019ancien Comt\u00e9 de Champagne \u2013 au rayonnement\u00a0national et international. Il ne subsiste pourtant aucun vestige physique des lieux de vie de ces communaut\u00e9s. Mais les noms de leurs repr\u00e9sentants ont travers\u00e9 les si\u00e8cles et les fronti\u00e8res et sont mondialement connus sous le terme des \u00ab Sages de Champagne \u00bb. Les plus connus ont r\u00e9sid\u00e9 \u00e0 Ramerupt et Dampierre, deux communes de la Communaut\u00e9 de Communes d\u2019Arcis-Mailly-Ramerupt (CCAMR) situ\u00e9e au nord de l\u2019Aube, ce qui explique l\u2019emplacement des trois premi\u00e8res fresques.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<h3 style=\"text-align: left;\"><strong>L\u2019esprit du parcours Rachi<\/strong><\/h3>\n[\/vc_column_text][vc_column_text]Dans un contexte de patrimoine immat\u00e9riel, l\u2019id\u00e9e d\u2019illustrer le patrimoine juif m\u00e9di\u00e9val de l\u2019Aube par le biais d\u2019\u0153uvres artistiques p\u00e9rennes, gratuites et ouvertes \u00e0 tous, a pour objectif de rendre ce pan de l\u2019histoire locale accessible au grand public pour permettre, outre la d\u00e9couverte de l\u2019histoire de l\u2019Aube, une meilleure compr\u00e9hension du patrimoine juif et de la culture juive de mani\u00e8re informelle, en croisant art et patrimoine historique de fa\u00e7on ludique.<\/p>\n<p>Dans ce cadre, ce circuit de slowtourisme prend tout son sens d\u2019un point de vue touristique et culturel en m\u00eame temps que dans une logique de valorisation du territoire.<\/p>\n<p>Ce projet gratuit et destin\u00e9 \u00e0 tous les publics, habitants comme touristes, est largement inclusif autour d\u2019une histoire locale oubli\u00e9e. En impliquant les habitants et en particulier les publics scolaires dans sa r\u00e9alisation au travers de nombreux ateliers, il a \u0153uvr\u00e9 \u00e0 faire reconnaitre ce patrimoine local majeur et \u00e0 lutter contre l\u2019antis\u00e9mitisme.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb61599&Prime; img_size=\u00a0\u00bb568&#215;380&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb61602&Prime; img_size=\u00a0\u00bb568&#215;380&Prime; alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/www.aube-champagne.com\/fr\/poi\/montgolfiere-du-lac-d-orient\/\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner][vc_column_text]\n<h3 style=\"text-align: left;\"><strong>Le r\u00f4le du Conseil Scientifique de la Route m\u00e9di\u00e9vale de Rachi en Champagne<\/strong><\/h3>\n[\/vc_column_text][vc_column_text]Le travail de narration de la fresque a \u00e9t\u00e9 propos\u00e9 par CulturistiQ Laboratoire Culturel et encadr\u00e9 le Conseil scientifique de la Route m\u00e9di\u00e9vale de Rachi en Champagne, constitu\u00e9 d\u2019une \u00e9quipe de chercheurs d\u2019excellence :<\/p>\n<ul>\n<li>Arnaud Baudin, Directeur adjoint des Archives et du Patrimoine de l\u2019Aube, Docteur en histoire m\u00e9di\u00e9vale<\/li>\n<li>Marc-Alain Ouaknin, Rabbin, \u00e9crivain et professeur de philosophie et litt\u00e9rature compar\u00e9e \u00e0 l\u2019Universit\u00e9 Bar-Ilan (Isra\u00ebl)<\/li>\n<li>Pinchas Roth, Professeur d\u2019histoire juive m\u00e9di\u00e9vale, D\u00e9partement Talmud \u00e0 l\u2019Universit\u00e9 de Bar Ilan, sp\u00e9cialiste d\u2019Isaac de Dampierre<\/li>\n<li>Dani\u00e8le Sansy, Ma\u00eetresse de conf\u00e9rences en histoire m\u00e9di\u00e9vale \u00e0 l\u2019Universit\u00e9 Le Havre Normandie<\/li>\n<\/ul>\n<p>L\u2019\u00e9quipe a \u00e9t\u00e9 accompagn\u00e9e ponctuellement par Judith Kogel, Directrice de recherches \u00e0 l\u2019IRHT (Institut de Recherche et d\u2019Histoire des Textes), et les Professeurs Rami Reiner (Universit\u00e9 Ben Gourion) et Claire Soussen (Universit\u00e9 Boulogne C\u00f4te d\u2019Opale et Directrice de la Nouvelle Gallia Judaica)<\/p>\n<p>Les membres du groupe de travail ont valid\u00e9 la narration propos\u00e9e par la Route m\u00e9di\u00e9vale de Rachi en Champagne sur le th\u00e8me de la \u00ab M\u00e9moire des Sages de Champagne\u00a0\u00bb qui s\u2019est articul\u00e9e autour d\u2019une rencontre entre symbolique champenoise m\u00e9di\u00e9vale et symbolique du patrimoine et de l\u2019histoire juive locale. L\u2019expertise du conseil scientifique a \u00e9t\u00e9 particuli\u00e8rement sollicit\u00e9e pour la coh\u00e9rence des d\u00e9tails historiques et de la symbolique, ainsi que la validation des choix du verset et de la traduction du commentaire figurant sur la fresque.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00a0\u00bb16px\u00a0\u00bb][vc_separator color=\u00a0\u00bborange\u00a0\u00bb el_width=\u00a0\u00bb30&Prime;][vc_empty_space height=\u00a0\u00bb16px\u00a0\u00bb][vc_row_inner][vc_column_inner][vc_column_text]\n<h2 style=\"text-align: left;\"><strong>La fresque de Lhu\u00eetre. Une rencontre entre art et histoire<\/strong><\/h2>\n[\/vc_column_text][vc_column_text]La maquette de la fresque de Lhu\u00eetre a \u00e9t\u00e9 r\u00e9alis\u00e9e un artiste fresquiste de renom, Jean-Jacques Jolinon.<\/p>\n<p>Initi\u00e9 au travail de la chaux par un grand-p\u00e8re ma\u00e7on, il conserve le souvenir de sa Tunisie natale aux maisons badigeonn\u00e9es de couleurs pastel. Apr\u00e8s avoir v\u00e9cu aux \u00c9tats-Unis et au Mexique, o\u00f9 il est impressionn\u00e9 et s\u00e9duit par le mouvement muraliste, il n\u2019a qu\u2019une obsession\u00a0: la r\u00e9habilitation et la transmission de la fresque.<\/p>\n<p>Il s\u2019installe dans la Vienne en 1981 o\u00f9 il dirige les ateliers de fresques \u00e0 l\u2019abbaye de Saint-Savin-sur-Gartempe dans le cadre du Centre international d\u2019art mural, jusqu\u2019\u00e0 sa fermeture en 2003. Il continue des chantiers de formation \u00e0 l\u2019abbaye royale de Saint-Jean-d\u2019Ang\u00e9ly, \u00e0 la Chambre des M\u00e9tiers d\u2019Aurillac, dans des lyc\u00e9es de Poitiers et de Troyes.<\/p>\n<p>C&rsquo;est \u00e0 Saint-Jean-d&rsquo;Ang\u00e9ly qu&rsquo;il rencontre les enseignants qui fondent en 2003, l&rsquo;association des Passeurs de Fresques dont l&rsquo;objet principal est la transmission de cet art ancestral. Il les forme, les accompagne, les soutient dans leurs actions depuis 20 ans.<\/p>\n<p>Parall\u00e8lement \u00e0 son activit\u00e9 de formateur, il r\u00e9alise de nombreuses fresques chez des particuliers, \u00e0 la Saline royale d\u2019Arc-et-Senans, dans le hall d\u2019entr\u00e9e du CHU de Poitiers, dans des mairies (Saint-Savin sur Gartempe, Chauvigny).<\/p>\n<p>Dans l&rsquo;Aube, il a cr\u00e9\u00e9 et r\u00e9alis\u00e9 les fresques de l&rsquo;IUMP (Troyes, 2007), de la salle socio-culturelle de Faux-Villecerf (2010), de la grange du moulin de Dosches (2013) et de l&rsquo;ancienne Bourse du Travail (Troyes, 2022)<\/p>\n<p>La r\u00e9alisation de la fresque a \u00e9t\u00e9 confi\u00e9e \u00e0 l\u2019association auboise \u00ab\u00a0<strong>Les Passeurs de fresques<\/strong>\u00a0\u00bb. Les b\u00e9n\u00e9voles utilisent cet art antique qui est une technique de peinture sur un enduit frais constitu\u00e9 de chaux a\u00e9rienne et de sable de rivi\u00e8re. Les couleurs appliqu\u00e9es sont des pigments naturels, compatibles avec la chaux, simplement d\u00e9lay\u00e9s dans l\u2019eau.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb61605&Prime; img_size=\u00a0\u00bb568&#215;380&Prime;][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb61611&Prime; img_size=\u00a0\u00bb568&#215;380&Prime;][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb61608&Prime; img_size=\u00a0\u00bb568&#215;380&Prime;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]\n<h3 style=\"text-align: left;\"><strong>Comment se r\u00e9alise une fresque\u00a0?<\/strong><\/h3>\n[\/vc_column_text][vc_column_text]Une fois la maquette de la fresque r\u00e9alis\u00e9e par l\u2019artiste, les fresquistes l\u2019agrandissent \u00e0 l\u2019\u00e9chelle. Le calque plastique utilis\u00e9 pour cette op\u00e9ration est ensuite positionn\u00e9 sur le mur pr\u00e9alablement pr\u00e9par\u00e9 et permet d\u2019apposer le trac\u00e9, puis au fur et \u00e0 mesure les pigments souhait\u00e9s. Une op\u00e9ration pour un chantier tel que la fresque de Dampierre n\u00e9cessite cinq jours pleins de travail sur site, sans compter les travaux pr\u00e9alables d\u2019agrandissement de la maquette et le choix des couleurs.<\/p>\n<p>Pour plus d\u2019informations\u00a0: <a href=\"http:\/\/lespasseursdefresques.fr\/\">http:\/\/lespasseursdefresques.fr\/<\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]\n<h3 style=\"text-align: left;\"><strong>Le chantier de la fresque de Lhu\u00eetre<\/strong><\/h3>\n[\/vc_column_text][vc_column_text]Le projet de fresque de Lhu\u00eetre a \u00e9t\u00e9 port\u00e9 par la Communaut\u00e9 de Communes Arcis Mailly Ramerupt, conjointement avec celui de Dampierre et Ramerupt. La commune de Lhu\u00eetre a montr\u00e9 un vif int\u00e9r\u00eat \u00e0 revaloriser son patrimoine m\u00e9di\u00e9val et s\u2019est port\u00e9e candidate \u00e0 la r\u00e9alisation de cette troisi\u00e8me fresque du Parcours Rachi.<\/p>\n<p>La chaux est un mat\u00e9riau vivant qui s\u2019adapte mieux \u00e0 un mur en brique sain. Celui de la Mairie de la commune r\u00e9pondant \u00e0 ces crit\u00e8res a paru id\u00e9al au groupe de travail. Le choix d\u2019une fresque de grande dimension, visible gratuitement depuis la voirie communale a fait l\u2019unanimit\u00e9.<\/p>\n<p>La pr\u00e9sence d\u2019une dizaine de b\u00e9n\u00e9voles a \u00e9t\u00e9 n\u00e9cessaire pour r\u00e9aliser la fresque in situ. Les fresquistes \u00e9taient h\u00e9berg\u00e9s par la commune pendant toute la dur\u00e9e du chantier. Le chantier s\u2019est d\u00e9roul\u00e9 du 11 au 16 septembre 2023.\u00a0Apr\u00e8s la pose, de deux couches de chaux, le travail de report du dessin puis la phase de colorisation de l\u2019\u0153uvre a pu commencer \u00e0 l\u2019aide d\u2019un \u00e9chafaudage pos\u00e9 par la municipalit\u00e9.[\/vc_column_text][vc_btn title=\u00a0\u00bbT\u00e9l\u00e9charger le d\u00e9pliant \u00ab\u00a0Parcours Rachi\u00ab\u00a0\u00a0\u00bb color=\u00a0\u00bborange\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Fwww.aube-champagne.com%2Fassets%2Fuploads%2F2026%2F02%2FDepliant-Parcours-Rachi_FR-compressed.pdf|target:_blank\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\u00a0\u00bb16px\u00a0\u00bb][vc_separator color=\u00a0\u00bborange\u00a0\u00bb el_width=\u00a0\u00bb30&Prime;][vc_empty_space height=\u00a0\u00bb16px\u00a0\u00bb][vc_row_inner][vc_column_inner][vc_column_text]\n<h2 style=\"text-align: center;\"><strong>Les partenaires du projet<\/strong><\/h2>\n[\/vc_column_text][vc_column_text]\n<p style=\"text-align: center;\">Ce projet port\u00e9 par la Communaut\u00e9 de Communes Arcis Mailly Ramerupt a retenu l\u2019attention d\u2019institutions publiques et priv\u00e9es qui ont soutenu la cr\u00e9ation de la fresque.<\/p>\n<p style=\"text-align: center;\">Au travers du concours d\u2019Id\u00e9es 2021 et 2022 organis\u00e9 par l\u2019Agence d\u00e9partementale de tourisme de l\u2019Aube et de l\u2019appui du Minist\u00e8re de la Culture et du Conseil d\u00e9partemental de l\u2019Aube, l\u2019engagement de la Fondation pour la M\u00e9moire de la Shoah, de la Fondation du Juda\u00efsme Fran\u00e7ais et de la DILCRAH est significatif d\u2019une reconnaissance historique, civique et p\u00e9dagogique du projet.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text]\n<h3 style=\"text-align: center;\">Cela peut vous int\u00e9resser :<\/h3>\n[\/vc_column_text][vc_basic_grid post_type=\u00a0\u00bbpost\u00a0\u00bb max_items=\u00a0\u00bb3&Prime; style=\u00a0\u00bbpagination\u00a0\u00bb items_per_page=\u00a0\u00bb3&Prime; gap=\u00a0\u00bb25&Prime; paging_design=\u00a0\u00bbpagination_rounded\u00a0\u00bb paging_color=\u00a0\u00bbblack\u00a0\u00bb item=\u00a0\u00bb43199&Prime; grid_id=\u00a0\u00bbvc_gid:1771256519858-dc077b12-6c12-10&Prime;][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_single_image image=\u00a0\u00bb69125&Prime; img_size=\u00a0\u00bb2048&#215;1200&Prime;][vc_row_inner][vc_column_inner][vc_column_text] La fresque \u00ab\u00a0Rachi, ses disciples et ses filles \u00bb, cr\u00e9\u00e9e en septembre 2023, raconte et met en valeur le patrimoine juif m\u00e9di\u00e9val de Lhu\u00eetre o\u00f9 une communaut\u00e9 juive est install\u00e9e au Moyen-\u00c2ge du temps des comtes de Champagne. \u00a0Cette fresque est la&hellip;  <a href=\"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/\" title=\"Read Parcours Rachi : La fresque de Lhu\u00eetre\">En savoir plus&raquo;<\/a><\/p>\n","protected":false},"author":9192237,"featured_media":61614,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-61579","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La fresque de Lhu\u00eetre | Aube en Champagne<\/title>\n<meta name=\"description\" content=\"La fresque \u00ab\u00a0Rachi, ses disciples et ses filles \u00bb, cr\u00e9\u00e9e en septembre 2023, raconte et met en valeur le patrimoine juif m\u00e9di\u00e9val de Lhu\u00eetre o\u00f9 une communaut\u00e9 juive est install\u00e9e au Moyen-\u00c2ge du temps des comtes de Champagne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La fresque de Lhu\u00eetre | Aube en Champagne\" \/>\n<meta property=\"og:description\" content=\"La fresque \u00ab\u00a0Rachi, ses disciples et ses filles \u00bb, cr\u00e9\u00e9e en septembre 2023, raconte et met en valeur le patrimoine juif m\u00e9di\u00e9val de Lhu\u00eetre o\u00f9 une communaut\u00e9 juive est install\u00e9e au Moyen-\u00c2ge du temps des comtes de Champagne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/\" \/>\n<meta property=\"og:site_name\" content=\"Aube Champagne\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aube.champagne\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-16T15:43:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aube-champagne.com\/assets\/uploads\/2023\/09\/IMG-20230905-WA0000-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"568\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AubeChampagne\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/la-fresque-de-lhuitre\\\/\",\"url\":\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/la-fresque-de-lhuitre\\\/\",\"name\":\"La fresque de Lhu\u00eetre | Aube en Champagne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/la-fresque-de-lhuitre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/la-fresque-de-lhuitre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aube-champagne.com\\\/assets\\\/uploads\\\/2023\\\/09\\\/IMG-20230905-WA0000-1.jpg\",\"datePublished\":\"2023-09-19T12:17:42+00:00\",\"dateModified\":\"2026-02-16T15:43:01+00:00\",\"description\":\"La fresque \u00ab\u00a0Rachi, ses disciples et ses filles \u00bb, cr\u00e9\u00e9e en septembre 2023, raconte et met en valeur le patrimoine juif m\u00e9di\u00e9val de Lhu\u00eetre o\u00f9 une communaut\u00e9 juive est install\u00e9e au Moyen-\u00c2ge du temps des comtes de Champagne.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/la-fresque-de-lhuitre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/la-fresque-de-lhuitre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/la-fresque-de-lhuitre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aube-champagne.com\\\/assets\\\/uploads\\\/2023\\\/09\\\/IMG-20230905-WA0000-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aube-champagne.com\\\/assets\\\/uploads\\\/2023\\\/09\\\/IMG-20230905-WA0000-1.jpg\",\"width\":568,\"height\":380},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/la-fresque-de-lhuitre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parcours Rachi : La fresque de Lhu\u00eetre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/\",\"name\":\"Aube Champagne\",\"description\":\"Aube Champagne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aube-champagne.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La fresque de Lhu\u00eetre | Aube en Champagne","description":"La fresque \u00ab\u00a0Rachi, ses disciples et ses filles \u00bb, cr\u00e9\u00e9e en septembre 2023, raconte et met en valeur le patrimoine juif m\u00e9di\u00e9val de Lhu\u00eetre o\u00f9 une communaut\u00e9 juive est install\u00e9e au Moyen-\u00c2ge du temps des comtes de Champagne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/","og_locale":"fr_FR","og_type":"article","og_title":"La fresque de Lhu\u00eetre | Aube en Champagne","og_description":"La fresque \u00ab\u00a0Rachi, ses disciples et ses filles \u00bb, cr\u00e9\u00e9e en septembre 2023, raconte et met en valeur le patrimoine juif m\u00e9di\u00e9val de Lhu\u00eetre o\u00f9 une communaut\u00e9 juive est install\u00e9e au Moyen-\u00c2ge du temps des comtes de Champagne.","og_url":"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/","og_site_name":"Aube Champagne","article_publisher":"https:\/\/www.facebook.com\/aube.champagne","article_modified_time":"2026-02-16T15:43:01+00:00","og_image":[{"width":568,"height":380,"url":"https:\/\/www.aube-champagne.com\/assets\/uploads\/2023\/09\/IMG-20230905-WA0000-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AubeChampagne","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/","url":"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/","name":"La fresque de Lhu\u00eetre | Aube en Champagne","isPartOf":{"@id":"https:\/\/www.aube-champagne.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/#primaryimage"},"image":{"@id":"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aube-champagne.com\/assets\/uploads\/2023\/09\/IMG-20230905-WA0000-1.jpg","datePublished":"2023-09-19T12:17:42+00:00","dateModified":"2026-02-16T15:43:01+00:00","description":"La fresque \u00ab\u00a0Rachi, ses disciples et ses filles \u00bb, cr\u00e9\u00e9e en septembre 2023, raconte et met en valeur le patrimoine juif m\u00e9di\u00e9val de Lhu\u00eetre o\u00f9 une communaut\u00e9 juive est install\u00e9e au Moyen-\u00c2ge du temps des comtes de Champagne.","breadcrumb":{"@id":"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/#primaryimage","url":"https:\/\/www.aube-champagne.com\/assets\/uploads\/2023\/09\/IMG-20230905-WA0000-1.jpg","contentUrl":"https:\/\/www.aube-champagne.com\/assets\/uploads\/2023\/09\/IMG-20230905-WA0000-1.jpg","width":568,"height":380},{"@type":"BreadcrumbList","@id":"https:\/\/www.aube-champagne.com\/fr\/la-fresque-de-lhuitre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.aube-champagne.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Parcours Rachi : La fresque de Lhu\u00eetre"}]},{"@type":"WebSite","@id":"https:\/\/www.aube-champagne.com\/fr\/#website","url":"https:\/\/www.aube-champagne.com\/fr\/","name":"Aube Champagne","description":"Aube Champagne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aube-champagne.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 22:01:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aube-champagne.com\/fr\/wp-json\/wp\/v2\/pages\/61579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aube-champagne.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.aube-champagne.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.aube-champagne.com\/fr\/wp-json\/wp\/v2\/users\/9192237"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aube-champagne.com\/fr\/wp-json\/wp\/v2\/comments?post=61579"}],"version-history":[{"count":5,"href":"https:\/\/www.aube-champagne.com\/fr\/wp-json\/wp\/v2\/pages\/61579\/revisions"}],"predecessor-version":[{"id":90878,"href":"https:\/\/www.aube-champagne.com\/fr\/wp-json\/wp\/v2\/pages\/61579\/revisions\/90878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aube-champagne.com\/fr\/wp-json\/wp\/v2\/media\/61614"}],"wp:attachment":[{"href":"https:\/\/www.aube-champagne.com\/fr\/wp-json\/wp\/v2\/media?parent=61579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}